{"id":373,"date":"2023-06-02T01:00:00","date_gmt":"2023-06-02T01:00:00","guid":{"rendered":"https:\/\/mytransgenderdate.com\/es\/blog\/?p=373"},"modified":"2025-07-13T06:57:02","modified_gmt":"2025-07-13T06:57:02","slug":"la-vida-de-crystal-labeija","status":"publish","type":"post","link":"https:\/\/mytransgenderdate.com\/es\/blog\/2023\/06\/la-vida-de-crystal-labeija","title":{"rendered":"La vida de Crystal LaBeija"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Luego de que la serie de televisi\u00f3n <em>Pose<\/em> se convirtiera en todo un \u00e9xito, el inter\u00e9s de la gente en la cultura <em>ball <\/em>comenz\u00f3 a crecer exponencialmente. La cultura <em>ball<\/em>, tambi\u00e9n conocida como \u201cla escena del <em>ballroom\u201d<\/em>, es el \u00e1mbito de las fiestas <em>underground <\/em>de Nueva York de las d\u00e9cadas de 1990 y 2000. All\u00ed sol\u00edan ir drag queens afroamericanas y latinas quienes, por causa del racismo, eran excluidas de los circuitos drag.<\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Crystal LaBeija: The Story of a Drag Icon \ud83d\udc83\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/3LwjQOh392E?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>Nota:<\/strong>\u00a0Este v\u00eddeo se presenta en ingl\u00e9s. Para ayudar a nuestros lectores hispanohablantes, puede\u00a0<strong>activar los subt\u00edtulos traducidos autom\u00e1ticamente<\/strong>\u00a0haciendo clic en el icono de configuraci\u00f3n [\u2699\ufe0f] en el reproductor de v\u00eddeo, seleccionando \u00abSubt\u00edtulos\/CC\u00bb, luego \u00abIngl\u00e9s (generado autom\u00e1ticamente)\u00bb, despu\u00e9s \u00abSubt\u00edtulos\u00bb, y finalmente eligiendo \u00abTraducir autom\u00e1ticamente\u00bb y su idioma preferido.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">El mundo del <em>ballroom <\/em>suele incluir concursos de belleza y presentaciones en las que la belleza alternativa y el entretenimiento cobran vida. Hoy vamos a hablar de <strong>la vida de Crystal LaBeija<\/strong>, una mujer trans conocida como \u201cla madre de la cultura ball\u201d por su importante rol en el desarrollo de esta subcultura.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Crystal LaBeija antes del <em>ballroom<\/em><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">No hay mucha informaci\u00f3n comprobable en internet sobre la infancia de Crystal, pero sabemos que <strong>naci\u00f3 en la d\u00e9cada de 1930<\/strong>. Antes de convertirse en la madre de la cultura ball, Crystal era una mujer trans negra y orgullosa de serlo.&nbsp;<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"506\" src=\"https:\/\/mytransgenderdate.com\/es\/blog\/wp-content\/uploads\/sites\/6\/2023\/05\/Crystal_LaBeija_before_The_Ballroom_Scene-edited.jpg\" alt=\"Crystal LaBeija en la pel\u00edcula &quot;The Queen&quot;, 1968\" class=\"wp-image-377\" srcset=\"https:\/\/mytransgenderdate.com\/es\/blog\/wp-content\/uploads\/sites\/6\/2023\/05\/Crystal_LaBeija_before_The_Ballroom_Scene-edited.jpg 900w, https:\/\/mytransgenderdate.com\/es\/blog\/wp-content\/uploads\/sites\/6\/2023\/05\/Crystal_LaBeija_before_The_Ballroom_Scene-edited-300x169.jpg 300w, https:\/\/mytransgenderdate.com\/es\/blog\/wp-content\/uploads\/sites\/6\/2023\/05\/Crystal_LaBeija_before_The_Ballroom_Scene-edited-768x432.jpg 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><figcaption class=\"wp-element-caption\"><em>Pel\u00edcula \u2013&nbsp;<a href=\"https:\/\/www.imdb.com\/title\/tt0063477\/\" target=\"_blank\" rel=\"noreferrer noopener\">The queen<\/a><\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\">El mundo de los concursos de belleza<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Como toda una verdadera reina madre, comenz\u00f3 su carrera como <strong>una reina de la belleza en el circuito drag de Manhattan<\/strong>. Su primer nombre art\u00edstico fue Crystal LaAsia, pero lo termin\u00f3 cambiando por LaBeija. En muchos de los elogios que recib\u00eda sol\u00edan decirle \u201cla belleza\u201d, algo que fue esencial para realizar este cambio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las d\u00e9cadas del 1960 y 1970 fueron a\u00f1os cargados con tanto racismo y colorismo que a muchas drag queens de color se les negaba el reconocimiento que merec\u00edan. Muchas de ellas, en vano, llegaron a blanquearse la piel con productos de maquillaje y cosm\u00e9tica para competir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, a pesar de la discriminaci\u00f3n que hab\u00eda en el mundo de los concursos de belleza, Crystal fue <strong>una de las pocas drag queens en ser nombrada<\/strong> \u201creina del baile\u201d. Muchos de los concursos drag eran organizados por drag queens blancas. M\u00e1s tarde, tambi\u00e9n lograr\u00eda romper con las barreras del color de piel al ser coronada Miss Manhattan.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">El esc\u00e1ndalo del concurso de belleza <em>Miss All-America Camp<\/em> de 1967<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Uno de los momentos m\u00e1s memorables dentro de las experiencias en concursos de belleza de Crystal LaBeija fue cuando compiti\u00f3 en la edici\u00f3n de 1967 del <strong>concurso de belleza <em>Miss All-America Camp<\/em><\/strong>. El evento tuvo lugar en el Town Hall en la ciudad de Nueva York y fue incluido en el documental <em><a href=\"https:\/\/www.imdb.com\/title\/tt0063477\/\" target=\"_blank\" rel=\"noreferrer noopener\">The Queen<\/a><\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La ganadora del concurso fue Rachel Harlow, una drag queen blanca. Insatisfecha con los resultados, Crystal fue grabada mientras acusaba a Flawless Sabrina, la organizadora del evento, de haber arreglado el concurso a favor de una drag queen blanca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Debido a otro resultado completamente injusto, se sinti\u00f3 inspirada a <strong>radicalizar el circuito drag de los concursos de belleza<\/strong>. Se asoci\u00f3 con Lottie LaBeija, otra drag queen negra, y organizaron un baile solo para drag queens negras.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La madre de la cultura ball&nbsp;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Crystal acept\u00f3 ser la anfitriona del evento siempre y cuando su presencia fuera destacada. Fue el primer evento organizado por una \u201ccasa\u201d y lo llamaron<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><em>Crystal &amp; Lottie LaBeija presentan el primer baile anual de House of LaBeija en Up the Downstairs Case en calle 115 oeste y la Quinta Avenida, en Harlem, Nueva York.<\/em><\/p>\n<\/blockquote>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1064\" height=\"598\" src=\"https:\/\/mytransgenderdate.com\/es\/blog\/wp-content\/uploads\/sites\/6\/2023\/05\/The_Mother_of_The_Ball_IMG_Src_Live_Out_Loud-edited.jpg\" alt=\"Crystal LaBeija en la pel\u00edcula &quot;The Queen&quot;, 1968\" class=\"wp-image-380\" srcset=\"https:\/\/mytransgenderdate.com\/es\/blog\/wp-content\/uploads\/sites\/6\/2023\/05\/The_Mother_of_The_Ball_IMG_Src_Live_Out_Loud-edited.jpg 1064w, https:\/\/mytransgenderdate.com\/es\/blog\/wp-content\/uploads\/sites\/6\/2023\/05\/The_Mother_of_The_Ball_IMG_Src_Live_Out_Loud-edited-300x169.jpg 300w, https:\/\/mytransgenderdate.com\/es\/blog\/wp-content\/uploads\/sites\/6\/2023\/05\/The_Mother_of_The_Ball_IMG_Src_Live_Out_Loud-edited-1024x576.jpg 1024w, https:\/\/mytransgenderdate.com\/es\/blog\/wp-content\/uploads\/sites\/6\/2023\/05\/The_Mother_of_The_Ball_IMG_Src_Live_Out_Loud-edited-768x432.jpg 768w\" sizes=\"auto, (max-width: 1064px) 100vw, 1064px\" \/><figcaption class=\"wp-element-caption\"><em>Movie &#8211; <a href=\"https:\/\/www.imdb.com\/title\/tt0063477\/\" target=\"_blank\" rel=\"noreferrer noopener\">The queen<\/a><\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">El evento, que sucedi\u00f3 en 1972, no solo fue crucial para destacar a las drag queens negras, sino que fue tambi\u00e9n el momento en que Crystal acu\u00f1\u00f3 el t\u00e9rmino <em>House <\/em>(\u201ccasa\u201d).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>House<\/em> era un t\u00e9rmino que las drag queens usaban para mostrar a qu\u00e9 grupo drag pertenec\u00edan. Por ejemplo, House of LaBeija era <strong>una de las casas m\u00e1s prominentes<\/strong> en la d\u00e9cada de 1970.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por suerte para ellas, el evento fue todo un \u00e9xito. Durante una presentaci\u00f3n en 1979, en un club nocturno, RuPaul, <strong>la drag queen m\u00e1s conocida<\/strong> de nuestra \u00e9poca, vio por primera vez un espect\u00e1culo drag. RuPaul cont\u00f3 c\u00f3mo vio a Crystal LaBeija haciendo <em>playback<\/em> en aquella ocasi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">[[SIGNUP]]<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Trabajo social y activismo<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Crystal fue una de las celebridades m\u00e1s abiertas a la hora de hablar sobre el transgenerismo y la discriminacion que las mujeres trans de color enfrentan. Adem\u00e1s de realizar espect\u00e1culos durante las d\u00e9cadas de 1970 y 1980, <strong>tambi\u00e9n particip\u00f3 en muchos movimientos<\/strong> a favor de las personas transg\u00e9nero.&nbsp;<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"720\" src=\"https:\/\/mytransgenderdate.com\/es\/blog\/wp-content\/uploads\/sites\/6\/2023\/05\/Social_Work_and_Activism_IMG_Src_AfroDiaspores-edited.jpg\" alt=\"Crystal LaBeija en la pel\u00edcula &quot;The Queen&quot;, 1968\" class=\"wp-image-382\" srcset=\"https:\/\/mytransgenderdate.com\/es\/blog\/wp-content\/uploads\/sites\/6\/2023\/05\/Social_Work_and_Activism_IMG_Src_AfroDiaspores-edited.jpg 1280w, https:\/\/mytransgenderdate.com\/es\/blog\/wp-content\/uploads\/sites\/6\/2023\/05\/Social_Work_and_Activism_IMG_Src_AfroDiaspores-edited-300x169.jpg 300w, https:\/\/mytransgenderdate.com\/es\/blog\/wp-content\/uploads\/sites\/6\/2023\/05\/Social_Work_and_Activism_IMG_Src_AfroDiaspores-edited-1024x576.jpg 1024w, https:\/\/mytransgenderdate.com\/es\/blog\/wp-content\/uploads\/sites\/6\/2023\/05\/Social_Work_and_Activism_IMG_Src_AfroDiaspores-edited-768x432.jpg 768w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><figcaption class=\"wp-element-caption\"><em>Movie &#8211; <a href=\"https:\/\/www.imdb.com\/title\/tt0063477\/\" target=\"_blank\" rel=\"noreferrer noopener\">The queen<\/a><\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">No solo fue una de las caras y voces que representaban los derechos de las personas transg\u00e9nero; su instinto maternal la llev\u00f3 a abrazar a una juventud desamparada dentro de la comunidad LGBTQIA+. Era conocida por ser tanto una madre drag como una verdadera madre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De manera informal, <strong>adoptaba a personas que hab\u00edan sido rechazadas por sus familias<\/strong> y les ofrec\u00eda un lugar para quedarse. Incluso hasta el 2022, Royal House of LaBeija (Casa Real de LaBeija) segu\u00eda triunfando y lleg\u00f3 a ganar siete trofeos en los premios NYC Ballroom Awards Ball.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La muerte de Crystal LaBeija<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Crystal <strong>muri\u00f3 en 1982<\/strong> de insuficiencia hep\u00e1tica, seg\u00fan inform\u00f3 la revista <em>Rolling Stone<\/em> en 2019. Pero el <em>New York Times<\/em> desminti\u00f3 esa informaci\u00f3n y declar\u00f3 que ella segu\u00eda viva en 1983 y que hab\u00eda sido vista en el reestreno de <em>The Queen<\/em> en el cine Film Forum de Nueva York.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hay rumores en internet que especulan que muri\u00f3 debido al consumo de medicamentos experimentales durante una <a href=\"https:\/\/mytransgenderdate.com\/es\/blog\/2023\/01\/que-es-la-terapia-hormonal-transgenero\">terapia de reemplazo hormonal<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Su legado<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Existen muchos documentales y otros contenidos en medios que le rindieron tributo a Crystal LaBeija. Algunas de las pel\u00edculas que hicieron referencia a su vida y fueron basadas en ella son:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><em>The Queen Who Reinvented Ball Culture<\/em><\/li>\n\n\n\n<li><em>The Queen<\/em> (Documental de 1968)<\/li>\n\n\n\n<li><em>Paris is Burning<\/em><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">En cuanto a la industria de la televisi\u00f3n y el cine, Crystal tuvo una gran influencia en los proyectos de <em>RuPaul\u2019s<\/em> <em>Drag Race<\/em> y <em>Pose<\/em>. Beyonce, una de las cantantes y artistas m\u00e1s famosas del mundo, coment\u00f3 que para su disco <em>Renaissance <\/em>se hab\u00eda inspirado en la cultura<em> ball.<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Royal House of LaBeija y la cultura <em>ball <\/em>luego del 2020<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e1s all\u00e1 de los medios, el legado de Crystal LaBeija brilla en la cultura del <em>ballroom <\/em>actual. Se siguen realizando muchos bailes en los Estados Unidos, y los m\u00e1s importantes son los de Nueva York. Hace poco, <strong>el 25 de octubre de 2022<\/strong>, Royal House of LaBeija recibi\u00f3 siete trofeos en el evento NYC Ballroom Awards Ball.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"422\" src=\"https:\/\/mytransgenderdate.com\/es\/blog\/wp-content\/uploads\/sites\/6\/2023\/05\/The_Royal_House_of_LaBeija_and_The_Ball_Culture_after_2020_IMG_Src_Royal_House_of_LaBeija_Com-edited.jpg\" alt=\"Crystal LaBeija en la pel\u00edcula &quot;The Queen&quot;, 1968\" class=\"wp-image-384\" srcset=\"https:\/\/mytransgenderdate.com\/es\/blog\/wp-content\/uploads\/sites\/6\/2023\/05\/The_Royal_House_of_LaBeija_and_The_Ball_Culture_after_2020_IMG_Src_Royal_House_of_LaBeija_Com-edited.jpg 750w, https:\/\/mytransgenderdate.com\/es\/blog\/wp-content\/uploads\/sites\/6\/2023\/05\/The_Royal_House_of_LaBeija_and_The_Ball_Culture_after_2020_IMG_Src_Royal_House_of_LaBeija_Com-edited-300x169.jpg 300w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption class=\"wp-element-caption\">LaBeija website &#8211; <a href=\"https:\/\/www.royalhouseoflabeija.com\/post\/royal-house-of-labeija-takes-seven-trophies-at-2022-nyc-ballroom-awards-ball\" target=\"_blank\" rel=\"noreferrer noopener\">Royal House of LaBeija Takes Seven Trophies at 2022 NYC Ballroom Awards Ball<\/a><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Zero LaBeija, uno de los integrantes de la casa, se llev\u00f3 los siguientes dos primeros premios: MF Sex Siren BQ JR (Figura masculina sirena sexual de hombre cisg\u00e9nero gay\/bi junior) y el MF Models Body \u201cHoliday Figures\u201d (Figura masculina de cuerpos de modelo \u201cFiguras festivas\u201d). Aja y Aoki LaBeija recibieron el primer premio a Legendary Runway with European Runway Understudy (Pasarela legendaria con suplente en pasarelas europeas).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras, Stephan LaBeija gan\u00f3 <strong>el primer premio MF Models Body \u201cHoliday Figures\u00bb<\/strong> (Figura masculina de cuerpos de modelo \u201cFiguras festivas\u201d). Pippi LaBeija tambi\u00e9n deslumbr\u00f3 a los jueces y recibi\u00f3 un merecido primer premio en la categor\u00eda <strong>Virgin Runway (Primeriza en la pasarela) del concurso<\/strong>. Por \u00faltimo, Frida LaBeija gan\u00f3 <strong>el primer premio Old Way (A la antigua) del concurso<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s de ganar trofeos, los miembros de la casa Zenith, Kuresha Kurenai Vintage y Marcus LaBeija recibieron menciones honorables en <strong>los premios Best Dressed (Mejor vestida) y BQ Vogue Fem (Presentaci\u00f3n femenina de hombre cisg\u00e9nero gay\/bi)<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luego de que la serie de televisi\u00f3n Pose se convirtiera en todo un \u00e9xito, el inter\u00e9s de la gente en la cultura ball comenz\u00f3 a crecer exponencialmente. La cultura ball, tambi\u00e9n conocida como \u201cla escena del ballroom\u201d, es el \u00e1mbito de las fiestas underground de Nueva York de las d\u00e9cadas de 1990 y 2000. All\u00ed [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":374,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[14],"class_list":["post-373","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-influencers","tag-featured"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La vida de Crystal LaBeija - My Transgender Blog<\/title>\n<meta name=\"description\" content=\"Hoy vamos a hablar de la vida de Crystal LaBeija, una mujer trans conocida como \u201cla madre de la cultura ball\u201d por su importante rol en el desarrollo de esta subcultura.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mytransgenderdate.com\/es\/blog\/2023\/06\/la-vida-de-crystal-labeija\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La vida de Crystal LaBeija - My Transgender Blog\" \/>\n<meta property=\"og:description\" content=\"Hoy vamos a hablar de la vida de Crystal LaBeija, una mujer trans conocida como \u201cla madre de la cultura ball\u201d por su importante rol en el desarrollo de esta subcultura.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mytransgenderdate.com\/es\/blog\/2023\/06\/la-vida-de-crystal-labeija\" \/>\n<meta property=\"og:site_name\" content=\"My Transgender Blog\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-02T01:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-13T06:57:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mytransgenderdate.com\/es\/blog\/wp-content\/uploads\/sites\/6\/2023\/05\/Featured_Image_SRC_ytimg.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Amanda Valentine Dela Cruz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/x.com\/amandavdelacruz\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Amanda Valentine Dela Cruz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mytransgenderdate.com\\\/es\\\/blog\\\/2023\\\/06\\\/la-vida-de-crystal-labeija#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mytransgenderdate.com\\\/es\\\/blog\\\/2023\\\/06\\\/la-vida-de-crystal-labeija\"},\"author\":{\"name\":\"Amanda Valentine Dela Cruz\",\"@id\":\"https:\\\/\\\/mytransgenderdate.com\\\/es\\\/blog\\\/#\\\/schema\\\/person\\\/4a539c6eb4c5ea1eae736bc6f474722e\"},\"headline\":\"La vida de Crystal LaBeija\",\"datePublished\":\"2023-06-02T01:00:00+00:00\",\"dateModified\":\"2025-07-13T06:57:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mytransgenderdate.com\\\/es\\\/blog\\\/2023\\\/06\\\/la-vida-de-crystal-labeija\"},\"wordCount\":1342,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/mytransgenderdate.com\\\/es\\\/blog\\\/2023\\\/06\\\/la-vida-de-crystal-labeija#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mytransgenderdate.com\\\/es\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/05\\\/Featured_Image_SRC_ytimg.jpg\",\"keywords\":[\"featured\"],\"articleSection\":[\"Influencers\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mytransgenderdate.com\\\/es\\\/blog\\\/2023\\\/06\\\/la-vida-de-crystal-labeija#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mytransgenderdate.com\\\/es\\\/blog\\\/2023\\\/06\\\/la-vida-de-crystal-labeija\",\"url\":\"https:\\\/\\\/mytransgenderdate.com\\\/es\\\/blog\\\/2023\\\/06\\\/la-vida-de-crystal-labeija\",\"name\":\"La vida de Crystal LaBeija - My Transgender Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mytransgenderdate.com\\\/es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mytransgenderdate.com\\\/es\\\/blog\\\/2023\\\/06\\\/la-vida-de-crystal-labeija#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mytransgenderdate.com\\\/es\\\/blog\\\/2023\\\/06\\\/la-vida-de-crystal-labeija#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mytransgenderdate.com\\\/es\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/05\\\/Featured_Image_SRC_ytimg.jpg\",\"datePublished\":\"2023-06-02T01:00:00+00:00\",\"dateModified\":\"2025-07-13T06:57:02+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/mytransgenderdate.com\\\/es\\\/blog\\\/#\\\/schema\\\/person\\\/4a539c6eb4c5ea1eae736bc6f474722e\"},\"description\":\"Hoy vamos a hablar de la vida de Crystal LaBeija, una mujer trans conocida como \u201cla madre de la cultura ball\u201d por su importante rol en el desarrollo de esta subcultura.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mytransgenderdate.com\\\/es\\\/blog\\\/2023\\\/06\\\/la-vida-de-crystal-labeija#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mytransgenderdate.com\\\/es\\\/blog\\\/2023\\\/06\\\/la-vida-de-crystal-labeija\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mytransgenderdate.com\\\/es\\\/blog\\\/2023\\\/06\\\/la-vida-de-crystal-labeija#primaryimage\",\"url\":\"https:\\\/\\\/mytransgenderdate.com\\\/es\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/05\\\/Featured_Image_SRC_ytimg.jpg\",\"contentUrl\":\"https:\\\/\\\/mytransgenderdate.com\\\/es\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/05\\\/Featured_Image_SRC_ytimg.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mytransgenderdate.com\\\/es\\\/blog\\\/2023\\\/06\\\/la-vida-de-crystal-labeija#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mytransgenderdate.com\\\/es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La vida de Crystal LaBeija\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mytransgenderdate.com\\\/es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/mytransgenderdate.com\\\/es\\\/blog\\\/\",\"name\":\"My Transgender Blog\",\"description\":\"El blog m\u00e1s informativo y entretenido sobre asuntos trans\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mytransgenderdate.com\\\/es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mytransgenderdate.com\\\/es\\\/blog\\\/#\\\/schema\\\/person\\\/4a539c6eb4c5ea1eae736bc6f474722e\",\"name\":\"Amanda Valentine Dela Cruz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/127737b0600db04b2fa568a8b7c1625a7e6933ae1eb06d928597b09b45e597e2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/127737b0600db04b2fa568a8b7c1625a7e6933ae1eb06d928597b09b45e597e2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/127737b0600db04b2fa568a8b7c1625a7e6933ae1eb06d928597b09b45e597e2?s=96&d=mm&r=g\",\"caption\":\"Amanda Valentine Dela Cruz\"},\"description\":\"Amanda Valentine is a transgender woman who has written about trans topics for over 10 years for My Transgender Date. She is an author who made it on Amazon\u2019s best-seller list by writing 5 books on trans women\u2019s relationships. Her book \u201cDating Transgender Women for Gentlemen\u201d peaked at #3 in the Transgender Studies category on Amazon. She started writing at the age of 10 and won a poetry contest in 4th grade which convinced her to pursue a career in literature. Her personal experiences as a transgender woman give her a unique perspective on trans topics.\",\"sameAs\":[\"https:\\\/\\\/dtwfgbook.abramspublishinghouse.com\",\"https:\\\/\\\/www.instagram.com\\\/amandavdelacruz\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/amanda-valentine-dela-cruz-82b5641a6\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/x.com\\\/amandavdelacruz\"],\"url\":\"https:\\\/\\\/mytransgenderdate.com\\\/es\\\/blog\\\/author\\\/amanda\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La vida de Crystal LaBeija - My Transgender Blog","description":"Hoy vamos a hablar de la vida de Crystal LaBeija, una mujer trans conocida como \u201cla madre de la cultura ball\u201d por su importante rol en el desarrollo de esta subcultura.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mytransgenderdate.com\/es\/blog\/2023\/06\/la-vida-de-crystal-labeija","og_locale":"es_ES","og_type":"article","og_title":"La vida de Crystal LaBeija - My Transgender Blog","og_description":"Hoy vamos a hablar de la vida de Crystal LaBeija, una mujer trans conocida como \u201cla madre de la cultura ball\u201d por su importante rol en el desarrollo de esta subcultura.","og_url":"https:\/\/mytransgenderdate.com\/es\/blog\/2023\/06\/la-vida-de-crystal-labeija","og_site_name":"My Transgender Blog","article_published_time":"2023-06-02T01:00:00+00:00","article_modified_time":"2025-07-13T06:57:02+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/mytransgenderdate.com\/es\/blog\/wp-content\/uploads\/sites\/6\/2023\/05\/Featured_Image_SRC_ytimg.jpg","type":"image\/jpeg"}],"author":"Amanda Valentine Dela Cruz","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/x.com\/amandavdelacruz","twitter_misc":{"Escrito por":"Amanda Valentine Dela Cruz","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mytransgenderdate.com\/es\/blog\/2023\/06\/la-vida-de-crystal-labeija#article","isPartOf":{"@id":"https:\/\/mytransgenderdate.com\/es\/blog\/2023\/06\/la-vida-de-crystal-labeija"},"author":{"name":"Amanda Valentine Dela Cruz","@id":"https:\/\/mytransgenderdate.com\/es\/blog\/#\/schema\/person\/4a539c6eb4c5ea1eae736bc6f474722e"},"headline":"La vida de Crystal LaBeija","datePublished":"2023-06-02T01:00:00+00:00","dateModified":"2025-07-13T06:57:02+00:00","mainEntityOfPage":{"@id":"https:\/\/mytransgenderdate.com\/es\/blog\/2023\/06\/la-vida-de-crystal-labeija"},"wordCount":1342,"commentCount":0,"image":{"@id":"https:\/\/mytransgenderdate.com\/es\/blog\/2023\/06\/la-vida-de-crystal-labeija#primaryimage"},"thumbnailUrl":"https:\/\/mytransgenderdate.com\/es\/blog\/wp-content\/uploads\/sites\/6\/2023\/05\/Featured_Image_SRC_ytimg.jpg","keywords":["featured"],"articleSection":["Influencers"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mytransgenderdate.com\/es\/blog\/2023\/06\/la-vida-de-crystal-labeija#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mytransgenderdate.com\/es\/blog\/2023\/06\/la-vida-de-crystal-labeija","url":"https:\/\/mytransgenderdate.com\/es\/blog\/2023\/06\/la-vida-de-crystal-labeija","name":"La vida de Crystal LaBeija - My Transgender Blog","isPartOf":{"@id":"https:\/\/mytransgenderdate.com\/es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mytransgenderdate.com\/es\/blog\/2023\/06\/la-vida-de-crystal-labeija#primaryimage"},"image":{"@id":"https:\/\/mytransgenderdate.com\/es\/blog\/2023\/06\/la-vida-de-crystal-labeija#primaryimage"},"thumbnailUrl":"https:\/\/mytransgenderdate.com\/es\/blog\/wp-content\/uploads\/sites\/6\/2023\/05\/Featured_Image_SRC_ytimg.jpg","datePublished":"2023-06-02T01:00:00+00:00","dateModified":"2025-07-13T06:57:02+00:00","author":{"@id":"https:\/\/mytransgenderdate.com\/es\/blog\/#\/schema\/person\/4a539c6eb4c5ea1eae736bc6f474722e"},"description":"Hoy vamos a hablar de la vida de Crystal LaBeija, una mujer trans conocida como \u201cla madre de la cultura ball\u201d por su importante rol en el desarrollo de esta subcultura.","breadcrumb":{"@id":"https:\/\/mytransgenderdate.com\/es\/blog\/2023\/06\/la-vida-de-crystal-labeija#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mytransgenderdate.com\/es\/blog\/2023\/06\/la-vida-de-crystal-labeija"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mytransgenderdate.com\/es\/blog\/2023\/06\/la-vida-de-crystal-labeija#primaryimage","url":"https:\/\/mytransgenderdate.com\/es\/blog\/wp-content\/uploads\/sites\/6\/2023\/05\/Featured_Image_SRC_ytimg.jpg","contentUrl":"https:\/\/mytransgenderdate.com\/es\/blog\/wp-content\/uploads\/sites\/6\/2023\/05\/Featured_Image_SRC_ytimg.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/mytransgenderdate.com\/es\/blog\/2023\/06\/la-vida-de-crystal-labeija#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mytransgenderdate.com\/es\/blog\/"},{"@type":"ListItem","position":2,"name":"La vida de Crystal LaBeija"}]},{"@type":"WebSite","@id":"https:\/\/mytransgenderdate.com\/es\/blog\/#website","url":"https:\/\/mytransgenderdate.com\/es\/blog\/","name":"My Transgender Blog","description":"El blog m\u00e1s informativo y entretenido sobre asuntos trans","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mytransgenderdate.com\/es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/mytransgenderdate.com\/es\/blog\/#\/schema\/person\/4a539c6eb4c5ea1eae736bc6f474722e","name":"Amanda Valentine Dela Cruz","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/127737b0600db04b2fa568a8b7c1625a7e6933ae1eb06d928597b09b45e597e2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/127737b0600db04b2fa568a8b7c1625a7e6933ae1eb06d928597b09b45e597e2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/127737b0600db04b2fa568a8b7c1625a7e6933ae1eb06d928597b09b45e597e2?s=96&d=mm&r=g","caption":"Amanda Valentine Dela Cruz"},"description":"Amanda Valentine is a transgender woman who has written about trans topics for over 10 years for My Transgender Date. She is an author who made it on Amazon\u2019s best-seller list by writing 5 books on trans women\u2019s relationships. Her book \u201cDating Transgender Women for Gentlemen\u201d peaked at #3 in the Transgender Studies category on Amazon. She started writing at the age of 10 and won a poetry contest in 4th grade which convinced her to pursue a career in literature. Her personal experiences as a transgender woman give her a unique perspective on trans topics.","sameAs":["https:\/\/dtwfgbook.abramspublishinghouse.com","https:\/\/www.instagram.com\/amandavdelacruz\/","https:\/\/www.linkedin.com\/in\/amanda-valentine-dela-cruz-82b5641a6\/","https:\/\/x.com\/https:\/\/x.com\/amandavdelacruz"],"url":"https:\/\/mytransgenderdate.com\/es\/blog\/author\/amanda"}]}},"_links":{"self":[{"href":"https:\/\/mytransgenderdate.com\/es\/blog\/wp-json\/wp\/v2\/posts\/373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mytransgenderdate.com\/es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mytransgenderdate.com\/es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mytransgenderdate.com\/es\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/mytransgenderdate.com\/es\/blog\/wp-json\/wp\/v2\/comments?post=373"}],"version-history":[{"count":6,"href":"https:\/\/mytransgenderdate.com\/es\/blog\/wp-json\/wp\/v2\/posts\/373\/revisions"}],"predecessor-version":[{"id":979,"href":"https:\/\/mytransgenderdate.com\/es\/blog\/wp-json\/wp\/v2\/posts\/373\/revisions\/979"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mytransgenderdate.com\/es\/blog\/wp-json\/wp\/v2\/media\/374"}],"wp:attachment":[{"href":"https:\/\/mytransgenderdate.com\/es\/blog\/wp-json\/wp\/v2\/media?parent=373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mytransgenderdate.com\/es\/blog\/wp-json\/wp\/v2\/categories?post=373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mytransgenderdate.com\/es\/blog\/wp-json\/wp\/v2\/tags?post=373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}